{"id":285865,"date":"2026-05-13T10:06:40","date_gmt":"2026-05-13T10:06:40","guid":{"rendered":"https:\/\/halkweb.com.tr\/?p=285865"},"modified":"2026-05-13T10:06:40","modified_gmt":"2026-05-13T10:06:40","slug":"verlorener-staub-des-staates","status":"publish","type":"post","link":"https:\/\/halkweb.com.tr\/de\/verlorener-staub-des-staates\/","title":{"rendered":"Die verlorene Richtlinie des Staates"},"content":{"rendered":"<p>Wenn man in die Vergangenheit blickt, sieht man manchmal nicht nur die Geschichte. Er sieht auch die Gegenwart.<\/p>\n<p>\u201cMaxime\u201d ist ein altes Wort. Aber was es beschreibt, ist eigentlich sehr vertraut. Wie das Ma\u00df im Inneren eines Menschen. Es ist wie der Teil von ihm, den er nicht bricht, auch wenn niemand ihn sieht. Wie der stille Zustand des Gewissens.<\/p>\n<p>Heute herrscht in der Gesellschaft eine gro\u00dfe Unruhe. Die Menschen sind nicht nur von der Schwierigkeit, \u00fcber die Runden zu kommen, \u00fcberw\u00e4ltigt. Vor allem sind sie zutiefst verletzt, wenn sie Ungerechtigkeit und den leichten Aufstieg unqualifizierter Personen sehen, die der Macht nahe sind.<\/p>\n<p>Am schmerzlichsten ist, dass Kinder und Jugendliche dies sehen.<\/p>\n<p>Wenn ein junger Mensch nicht glaubt, dass er durch Arbeit etwas erreichen kann, wird er nicht lange dort bleiben, wo er glaubt, dass er f\u00fcr seine Arbeit nicht belohnt wird. Denn die Menschen arbeiten nicht nur f\u00fcr Geld, sondern auch f\u00fcr ein Gef\u00fchl der Gerechtigkeit.<\/p>\n<p>Das Osmanische Reich ist nicht \u00fcber Nacht zusammengebrochen. Kriege allein haben das Osmanische Reich nicht zerst\u00f6rt. Zun\u00e4chst lockerte sich die innere Ordnung. Das Lehnswesen wurde geschw\u00e4cht. Das Steuersystem brach zusammen. Der Staat verlie\u00df sich mehr auf die Besteuerung, um Geld zu beschaffen. Einige Leute, die die Steuern eintreiben sollten, begannen, an ihre eigenen Interessen zu denken und nicht an den Staat. Die Last der Bauern wurde schwerer.<\/p>\n<p>Dann wurde das Verdienst korrumpiert. Nicht diejenigen, die ihre Arbeit gut machten, sondern diejenigen, die den M\u00e4chtigen nahestanden, traten in den Vordergrund. Selbst das Janitscharenkorps h\u00f6rte nach einer Weile auf, die Macht des Staates zu sein, und verwandelte sich in eine Struktur, die sich gegen Ver\u00e4nderungen wehrte. Der Staat begann nicht von au\u00dfen, sondern zuerst von innen zu erm\u00fcden.<\/p>\n<p>Die Schulden stiegen. Dann wurde D\u00fcyun-u Umumiyeh gegr\u00fcndet. Stellen Sie sich vor... Ein Staat wird zu einem Staat, in dem ein Teil des eigenen Einkommens von Ausl\u00e4ndern eingezogen wird. Wie viele Wunden sind f\u00fcr eine Nation schwerer als diese?<\/p>\n<p>Was wir als Zusammenbruch bezeichnen, kommt oft nicht auf einmal. Die Menschen gew\u00f6hnen sich an einige Fehler. Kleine Zugest\u00e4ndnisse werden zur Normalit\u00e4t. Das Schweigen w\u00e4chst. Eines Tages ist die Gesellschaft nicht mehr in der Lage zu erkennen, was sie verloren hat und wann.<\/p>\n<p>Heute sind die Menschen nicht nur mit dem Problem des Lebensunterhalts \u00fcberfordert. Die Sprache der st\u00e4ndigen Spannung, der Zustand des st\u00e4ndigen \u00c4rgers dr\u00fcckt auf die menschliche Seele. Denn wo kein Frieden ist, kann der Mensch nicht gesund denken. Gesellschaften, die in st\u00e4ndiger Angst leben, versuchen, den Tag zu retten, nicht zu produzieren.<\/p>\n<p>Aber eine Erholung ist immer noch m\u00f6glich.<\/p>\n<p>Manchmal f\u00e4ngt es damit an, dass ein Lehrer seine Arbeit richtig macht.<br \/>\nMit einem Richter, der sich nicht beugt.<br \/>\nVon einem Arzt, der sein Gewissen nicht verliert.<br \/>\nWenn eine Person rechtschaffen handelt, auch wenn niemand hinsieht...<\/p>\n<p>Denn das Motto ist das R\u00fcckgrat nicht nur des Staates, sondern auch des Menschen.<\/p>\n<p>Es ist nicht nur das Geld, das ein Land am Laufen h\u00e4lt.<br \/>\nDie Menschen k\u00f6nnen sich gegenseitig vertrauen.<\/p>\n<p>Sobald dieses Vertrauen weg ist,<br \/>\nselbst die gr\u00f6\u00dften Staaten beginnen von innen heraus zu zerfallen.<\/p>\n<p>Und der wahre Zusammenbruch eines Staates beginnt nicht, wenn die Staatskasse leer ist, sondern wenn die Menschen den Glauben an die Gerechtigkeit verlieren.<\/p>","protected":false},"excerpt":{"rendered":"<p>Der wahre Zusammenbruch eines Staates beginnt nicht, wenn die Staatskasse leer ist, sondern wenn die Menschen den Glauben an die Gerechtigkeit verlieren.<\/p>","protected":false},"author":23,"featured_media":285866,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[286],"tags":[289],"class_list":{"0":"post-285865","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-yazarlar","8":"tag-manset"},"_links":{"self":[{"href":"https:\/\/halkweb.com.tr\/de\/wp-json\/wp\/v2\/posts\/285865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/halkweb.com.tr\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/halkweb.com.tr\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/halkweb.com.tr\/de\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/halkweb.com.tr\/de\/wp-json\/wp\/v2\/comments?post=285865"}],"version-history":[{"count":1,"href":"https:\/\/halkweb.com.tr\/de\/wp-json\/wp\/v2\/posts\/285865\/revisions"}],"predecessor-version":[{"id":285867,"href":"https:\/\/halkweb.com.tr\/de\/wp-json\/wp\/v2\/posts\/285865\/revisions\/285867"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/halkweb.com.tr\/de\/wp-json\/wp\/v2\/media\/285866"}],"wp:attachment":[{"href":"https:\/\/halkweb.com.tr\/de\/wp-json\/wp\/v2\/media?parent=285865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/halkweb.com.tr\/de\/wp-json\/wp\/v2\/categories?post=285865"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/halkweb.com.tr\/de\/wp-json\/wp\/v2\/tags?post=285865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}