{"id":285859,"date":"2026-05-13T09:54:00","date_gmt":"2026-05-13T09:54:00","guid":{"rendered":"https:\/\/halkweb.com.tr\/?p=285859"},"modified":"2026-05-13T09:54:00","modified_gmt":"2026-05-13T09:54:00","slug":"heilige-wahrheit-und-macht","status":"publish","type":"post","link":"https:\/\/halkweb.com.tr\/de\/heilige-wahrheit-und-macht\/","title":{"rendered":"Das Heilige, die Wahrheit und die Macht"},"content":{"rendered":"<p>Es gibt S\u00e4tze, die liest man nicht nur, sie setzen sich im Kopf fest.<\/p>\n<p>Es verliert auch nach Jahrhunderten nicht seine Wirkung.<\/p>\n<p>Wie dieses Zitat, das Lucius Annaeus Seneca zugeschrieben wird:<\/p>\n<p>\u201cReligion ist f\u00fcr das gemeine Volk real, f\u00fcr die Weisen eine Fabel und f\u00fcr die M\u00e4chtigen n\u00fctzlich.\u201d<\/p>\n<p>Dieser Satz ist beunruhigend. Denn er gibt keine Antwort, er hinterl\u00e4sst eine Frage in den K\u00f6pfen der Menschen. Und vielleicht ist das, was wir Zivilisation nennen, auf der Geschichte dieser Fragen aufgebaut.<\/p>\n<p>Einer der \u00e4ltesten Zufluchtsorte in der Geschichte der Menschheit ist die Religion.<\/p>\n<p>Der Mensch hat sich seit seiner ersten Angst an das Unsichtbare geklammert. Denn das Leben war oft zu hart, um erkl\u00e4rt zu werden. Es gab den Tod. Es gab Hunger. Es gab Ungerechtigkeit. Der Mensch blickte in den Himmel, um nicht allein im Zentrum des Universums zu sein.<\/p>\n<p>Aus diesem Grund ist Religion nicht nur ein Glaubenssystem.<\/p>\n<p>Sie ist auch zu einem Trost, einer Zugeh\u00f6rigkeit und einer gro\u00dfen Sinnordnung inmitten des Chaos geworden.<\/p>\n<p>Vielleicht ist das der Grund, warum sie auch heute noch f\u00fcr Millionen von Menschen die absolute Wahrheit ist. Denn der Mensch ist nicht immer auf der Suche nach Wahrheit, sondern oft nach einem Sinn, auf den er sich verlassen kann.<\/p>\n<p>Aber die Geschichte hat sich irgendwann ge\u00e4ndert.<\/p>\n<p>Der Gedanke kam auf der B\u00fchne.<\/p>\n<p>Die Philosophen kamen.<\/p>\n<p>Die Wissenschaft ist angekommen.<\/p>\n<p>Es kam ein Verdacht auf.<\/p>\n<p>Und zum ersten Mal begann der Mensch, das Heilige zu hinterfragen:<\/p>\n<p>\u201cWas ist, wenn das, was uns gesagt wird, nicht die absolute Wahrheit ist?\u201d<\/p>\n<p>Hier begann einer der gr\u00f6\u00dften Br\u00fcche der Zivilisation. Denn der Verstand, der Fragen stellt, und die Struktur, die absoluten Gehorsam verlangt, haben sich nie vollst\u00e4ndig vers\u00f6hnen lassen.<\/p>\n<p>Hier muss jedoch eine wichtige Unterscheidung getroffen werden.<\/p>\n<p>Nur weil eine Erz\u00e4hlung symbolisch ist, ist sie noch lange nicht wertlos. Die Menschheit lebt nicht nur von nackten Tatsachen. Sie lebt auch von Mythen, Geschichten und gemeinsamen Annahmen.<\/p>\n<p>Wenn wir uns die moderne Welt von heute anschauen, sehen wir das deutlich.<\/p>\n<p>Es gibt weiterhin Nationen mit Heldengeschichten.<\/p>\n<p>Die Wirtschaft wird durch Mythen des Erfolgs angeheizt.<\/p>\n<p>Die Politik hingegen produziert st\u00e4ndig neue Heilige.<\/p>\n<p>Es geht also nicht nur um Religion.<\/p>\n<p>Es geht um das menschliche Bed\u00fcrfnis zu glauben.<\/p>\n<p>Der h\u00e4rteste Teil des Seneca zugeschriebenen Zitats ist jedoch dem Schluss vorbehalten:<\/p>\n<p>\u201cEs ist n\u00fctzlich f\u00fcr die Herrschenden\u201d.\u201d<\/p>\n<p>Hier beginnt die dunkle Seite der Geschichte.<\/p>\n<p>Denn keine Macht kann allein durch Gewalt \u00fcberleben. Der m\u00e4chtigste Weg, Menschen zu beherrschen, ist, ihre \u00c4ngste, ihr Gewissen und ihr Heiliges zu ber\u00fchren.<\/p>\n<p>Ein ver\u00e4ngstigter Mensch sucht Zuflucht.<\/p>\n<p>Wer Zuflucht nimmt, gehorcht.<\/p>\n<p>Und im Laufe der Geschichte hat keine Macht je ein so wirksames Instrument gefunden wie die Legitimit\u00e4t, die das Heilige bietet.<\/p>\n<p>K\u00f6nige sprachen im Namen Gottes.<\/p>\n<p>Armeen marschierten im Namen Gottes.<\/p>\n<p>Menschen, die im Namen Gottes get\u00f6tet wurden.<\/p>\n<p>Wieder starben Menschen im Namen Gottes.<\/p>\n<p>Was hat sich heute ge\u00e4ndert?<\/p>\n<p>Vielleicht haben sich nur die Fahrzeuge ge\u00e4ndert.<\/p>\n<p>Bildschirme haben Pal\u00e4ste ersetzt.<\/p>\n<p>Throne wurden durch Kanzeln ersetzt.<\/p>\n<p>Aber die Methode ist dieselbe geblieben.<\/p>\n<p>Denn die einfachste Politik ist immer noch, das Heilige in Politik zu verwandeln. Denn sobald es um Religion geht, verteidigen die Menschen ihre Identit\u00e4ten, nicht ihre Meinungen.<\/p>\n<p>Das Geheimnis der Macht ist genau hier verborgen.<\/p>\n<p>Der Glaube kann einen Menschen veredeln.<\/p>\n<p>Aber der organisierte Glaube kann manchmal zum funktionellsten Instrument der Macht werden.<\/p>\n<p>Vielleicht ist das der Grund, warum dieses Sprichwort auch nach zweitausend Jahren noch aktuell ist.<\/p>\n<p>Denn es geht nicht nur um die Frage der Existenz oder Nichtexistenz von Gott.<\/p>\n<p>Die Sache ist die:<\/p>\n<p>Warum glaubt der Mensch?<\/p>\n<p>Und was noch wichtiger ist.<\/p>\n<p>Wer bestimmt, was die Menschen glauben?<\/p>\n<p>Die Geschichte hat uns dies gezeigt:<\/p>\n<p>Diejenigen, die die Wahrheit suchen, und diejenigen, die die Wahrheit regieren, stehen oft nicht auf derselben Seite.<\/p>\n<p>Und die Menschheit steckt immer noch zwischen diesen beiden Seiten fest.<\/p>","protected":false},"excerpt":{"rendered":"<p>Diejenigen, die die Wahrheit suchen, und diejenigen, die die Wahrheit regieren, stehen oft nicht auf derselben Seite.<\/p>","protected":false},"author":51,"featured_media":285860,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[286],"tags":[289],"class_list":{"0":"post-285859","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-yazarlar","8":"tag-manset"},"_links":{"self":[{"href":"https:\/\/halkweb.com.tr\/de\/wp-json\/wp\/v2\/posts\/285859","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/halkweb.com.tr\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/halkweb.com.tr\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/halkweb.com.tr\/de\/wp-json\/wp\/v2\/users\/51"}],"replies":[{"embeddable":true,"href":"https:\/\/halkweb.com.tr\/de\/wp-json\/wp\/v2\/comments?post=285859"}],"version-history":[{"count":1,"href":"https:\/\/halkweb.com.tr\/de\/wp-json\/wp\/v2\/posts\/285859\/revisions"}],"predecessor-version":[{"id":285861,"href":"https:\/\/halkweb.com.tr\/de\/wp-json\/wp\/v2\/posts\/285859\/revisions\/285861"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/halkweb.com.tr\/de\/wp-json\/wp\/v2\/media\/285860"}],"wp:attachment":[{"href":"https:\/\/halkweb.com.tr\/de\/wp-json\/wp\/v2\/media?parent=285859"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/halkweb.com.tr\/de\/wp-json\/wp\/v2\/categories?post=285859"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/halkweb.com.tr\/de\/wp-json\/wp\/v2\/tags?post=285859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}